{"id":1205,"date":"2016-03-16T13:44:05","date_gmt":"2016-03-16T12:44:05","guid":{"rendered":"http:\/\/localhost:8888\/wordpress\/?p=1205"},"modified":"2022-03-06T19:39:30","modified_gmt":"2022-03-06T18:39:30","slug":"vrin-graubuenden-switzerland","status":"publish","type":"post","link":"https:\/\/www.ruralroadmap.eu\/de\/vrin-graubuenden-switzerland\/","title":{"rendered":"Vrin, Graub\u00fcnden, Schweiz"},"content":{"rendered":"<p>Die Gemeinde Vrin liegt in 1.450 Metern Seeh\u00f6he und z\u00e4hlt 250 EinwohnerInnen. Die Gesamtfl\u00e4che betr\u00e4gt 7.123 Hektar, davon sind 2.600 Hektar Alpenfl\u00e4che, 478 Hektar Waldfl\u00e4che, 300 Hektar Wiesen und nur zehn Hektar bleiben der der Siedlungsfl\u00e4che vorbehalten.<\/p>\n<p>Dass dieses abgelegene Bergdorf noch als aktive Agrargemeinde mit seit Jahren konstanter Bev\u00f6lkerung und einem beispielhaften Entwicklungsprozess existiert, ist einer Entscheidung aus dem Jahr 1979 zu verdanken, als der Exodus aus vielen Graub\u00fcndner Bergd\u00f6rfern in vollem Gang war und auch in Vrin die Einwohnerzahl von etwa 450 im Jahr 1950 auf ca. 270 sank. Damals gab die Pro Raetia &#8211; ein Verein, der b\u00fcndnerische Anliegen kultureller, sozialer und wirtschaftlicher Art f\u00f6rdert \u2013 den Ansto\u00df zur Gr\u00fcndung der Stiftung \u201ePro Vrin\u201c, deren Ziel es war, die kulturhistorische und architektonische Substanz zu bewahren sowie die Wohn- und Betriebsverh\u00e4ltnisse zu verbessern.<\/p>\n<p>1982 wurde mit der G\u00fcterzusammenlegung begonnen, um eine zukunftsorientierte Landwirtschaft zu erm\u00f6glichen. Dabei wurden auch der Ausbau des Stra\u00dfennetzes vorangetrieben und Ma\u00dfnahmen zur Veredelung und Vermarktung von einheimischen Produkten gesetzt. Die Gr\u00fcndung einer Genossenschaft zum Betrieb eines Schlachthauses und einer Metzgerei sowie zur Direktvermarktung des B\u00fcndner Trockenfleisches z\u00e4hlen ebenso dazu wie der Bau von Stallungen, einer Personalunterkunft und einer K\u00e4serei sowie die Vermarktung der Milchprodukte in einem Kiosk an einer rege frequentierten Wanderroute.<\/p>\n<p>Auch auf politischer Ebene wurden neue Akzente gesetzt. Man verzichtete auf den Ausbau eines Stausees in der Greina Hochebene und nahm stattdessen das Gebiet als Schutzzone ins Bundesinventar der Landschaften und Naturdenkm\u00e4ler der Schweiz auf. Die Aufforstung von 28 Hektar Schutzwald unter Mithilfe der Schulkinder und \u00f6rtlicher Vereine in den letzten zehn Jahren zeigt die Bem\u00fchungen zur St\u00e4rkung einer umweltgerechten Forstwirtschaft.<\/p>\n<p>Zu dieser Zeit entstand ein neues Bewusstsein f\u00fcr die eigenen Ressourcen und Potenziale. Neben der unber\u00fchrten Natur und einer in jahrhundertelanger Arbeit entstandenen Kulturlandschaft wurden sich die Vriner B\u00fcrgerInnen zunehmend ihrer beeindruckenden Bausubstanz bewusst, die es zu erhalten und weiterzuentwickeln galt. Der wesentliche Kern des heutigen Dorfes entstand in der zweiten H\u00e4lfte des 18.Jahrhunderts. Wohnh\u00e4user und St\u00e4lle, fast ausnahmslos Holzbauten in Blockkonstruktion, spiegeln die enge Verbundenheit mit der Landwirtschaft wider.<\/p>\n<p>Neben der Ausweisung von Bauzonen und dem Ankauf von Bauland durch die Gemeinde wurden wichtige Baurichtlinien erlassen. Bauten haben als gemeinsame Komponente die Ressource Holz. Die Verwendung heimischer Materialien und die Beauftragung regionaler Gewerbebetriebe generieren eine hohe Wertsch\u00f6pfung. Auch gemeindliche Bauma\u00dfnahmen wie die Stiva da morts (Totenhalle) und die Gemeindehalle spiegeln diese Philosophie wider.<\/p>\n<p>Neben einer Schule gibt es auch eine B\u00e4ckerei und ein Lebensmittelgesch\u00e4ft, bei denen die KonsumentInnen am Gewinn beteiligt und somit motiviert sind, im Ort einzukaufen. F\u00fcr die SeniorenInnen im Dorf werden von den Vereinen Mittagstische und andere Dienstleistungen organisiert<\/p>\n<p>Vrin ist gekennzeichnet durch zahlreiche, miteinander vernetzte Projekte, die wesentlich zur Wahrung der kulturhistorischen und architektonischen Substanz sowie zur Verbesserung der Wohn- und Betriebsverh\u00e4ltnisse beitragen. Dabei beeindrucken insbesondere die hohe architektonische Qualit\u00e4t, der Einsatz standortgerechter Materialien, die Ma\u00dfnahmen zur Direktvermarktung, die multifunktionale Mehrzweckhalle mit ihren innovativen Holzbaudetails und der Bau des Aufbahrungsraumes in der Ortsmitte als Indiz f\u00fcr das starke Miteinander der \u00f6rtlichen Gemeinschaft.<\/p>\n<p><em>Evaluiert: 2010<\/em><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-gallery-style=\"\" id='gallery-1' class='gallery galleryid-1205 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/11-Vrin-Vogelperspektive.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/11-Vrin-Vogelperspektive-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/Mehrzweckhalle.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/Mehrzweckhalle-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/MetzgereiStallungen.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/MetzgereiStallungen-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/Totenstube.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/Totenstube-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/VrinDorf.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/VrinDorf-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/Gemeindehaus-Vrin.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ruralroadmap.eu\/wp-content\/uploads\/2016\/03\/Gemeindehaus-Vrin-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Die Gemeinde Vrin liegt in 1.450 Metern Seeh\u00f6he und z\u00e4hlt 250 EinwohnerInnen. Die Gesamtfl\u00e4che betr\u00e4gt 7.123 Hektar, davon sind 2.600 Hektar Alpenfl\u00e4che, 478 Hektar Waldfl\u00e4che, 300 Hektar Wiesen und nur zehn Hektar bleiben der der Siedlungsfl\u00e4che vorbehalten. Dass dieses abgelegene Bergdorf noch als aktive Agrargemeinde mit seit Jahren konstanter Bev\u00f6lkerung und einem beispielhaften Entwicklungsprozess existiert,<br \/><a class=\"moretag\" href=\"https:\/\/www.ruralroadmap.eu\/de\/vrin-graubuenden-switzerland\/\">+ Lesen Sie mehr<\/a><\/p>\n","protected":false},"author":4,"featured_media":2702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[11,13,4,7,8,12,9,10,6],"tags":[],"class_list":["post-1205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baukultur-siedlungsentwicklung-kulturlandschaft","category-daseinsvorsorge-mobilitaet-digitalisierung","category-erholung-sport-kultur","category-kommunikation-partizipation","category-kooperationen-partnerschaften","category-oekologie-energie-ressourcen","category-oekonomie-regionalewertschoepfung-landundforstwirtschaft","category-orte","category-soziales-bildung-inklusion-integration"],"_links":{"self":[{"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/posts\/1205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":8,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"predecessor-version":[{"id":4756,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/posts\/1205\/revisions\/4756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/media\/2702"}],"wp:attachment":[{"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ruralroadmap.eu\/de\/wp-json\/wp\/v2\/tags?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}